{"id":15911,"date":"2026-05-06T13:02:10","date_gmt":"2026-05-06T13:02:10","guid":{"rendered":"https:\/\/lieschen-mueller.com\/about-us\/"},"modified":"2026-05-06T13:39:34","modified_gmt":"2026-05-06T13:39:34","slug":"about-us","status":"publish","type":"page","link":"https:\/\/lieschen-mueller.com\/en\/about-us\/","title":{"rendered":"About us"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"15911\" class=\"elementor elementor-15911 elementor-15756\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4cce1e3 elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"4cce1e3\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-42aa2c7\" data-id=\"42aa2c7\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a6dc978 elementor-widget elementor-widget-heading\" data-id=\"a6dc978\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">About us - Lieschen Mueller Cirque du Burlesque Bar, Adventure Restaurant &amp; Show Club at Alexanderplatz<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ad0ea39 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ad0ea39\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8230c6f\" data-id=\"8230c6f\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3ec30ed elementor-widget elementor-widget-heading\" data-id=\"3ec30ed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Our World of Burlesque &amp; Show Entertainment<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-79bc40d elementor-widget elementor-widget-text-editor\" data-id=\"79bc40d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Lieschen Mueller is Berlin&#8217;s crazy circus and burlesque bar directly under the TV tower &#8211; a restaurant, caf\u00e9 and show club all in one. An international burlesque and entertainment hotspot: a mix of bar, event location and show club where the &#8220;Cirque du Burlesque&#8221; world feels at home. Hundreds of cocktails, elaborate costumes, live acts and a legendary audience come together here and transform every evening into a glittering, fully booked show night.  <\/p><p>Between glitter, red curtains, circus details and a view of Alexanderplatz, a parallel world opens up every evening that is reminiscent of the wild 1920s: loud, cheeky, a little wicked &#8211; and guaranteed never to be boring.<\/p><p>During the day, Lieschen Mueller invites you to enjoy breakfast, coffee, cake and Berlin cuisine, while in the evening the location is transformed into a dazzling stage for the Cirque du Burlesque show &#8211; with dinner, cocktails and live entertainment in the heart of City East.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1b566fa elementor-widget elementor-widget-heading\" data-id=\"1b566fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Cirque du Burlesque - International Shows at the Television Tower<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-bff2a9c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bff2a9c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-87e8d44\" data-id=\"87e8d44\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e2163ae elementor-widget elementor-widget-image\" data-id=\"e2163ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/lieschen-mueller.com\/wp-content\/uploads\/2026\/05\/Kachel-Burlesque-Show-Champagner-Glas-Ueber-uns-1024x1024.webp\" class=\"attachment-large size-large wp-image-15903\" alt=\"\" srcset=\"https:\/\/lieschen-mueller.com\/wp-content\/uploads\/2026\/05\/Kachel-Burlesque-Show-Champagner-Glas-Ueber-uns-1024x1024.webp 1024w, https:\/\/lieschen-mueller.com\/wp-content\/uploads\/2026\/05\/Kachel-Burlesque-Show-Champagner-Glas-Ueber-uns-300x300.webp 300w, https:\/\/lieschen-mueller.com\/wp-content\/uploads\/2026\/05\/Kachel-Burlesque-Show-Champagner-Glas-Ueber-uns-150x150.webp 150w, https:\/\/lieschen-mueller.com\/wp-content\/uploads\/2026\/05\/Kachel-Burlesque-Show-Champagner-Glas-Ueber-uns-768x768.webp 768w, https:\/\/lieschen-mueller.com\/wp-content\/uploads\/2026\/05\/Kachel-Burlesque-Show-Champagner-Glas-Ueber-uns.webp 1200w\" sizes=\"(max-width: 800px) 100vw, 800px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9b8143e\" data-id=\"9b8143e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6f6e83e elementor-widget elementor-widget-text-editor\" data-id=\"6f6e83e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>The focus is on the <a href=\"https:\/\/lieschen-mueller.com\/en\/cirque-du-burlesque-show-berlin\/\">Cirque du Burlesque shows<\/a> with artists from Las Vegas, Canada, Rome, Madrid, Australia, the USA, England, Brazil and many other countries. Nikkie Lulaby, a classically trained event manager from the very beginning, is responsible for booking and managing this international ensemble. He creates coherent show evenings from casting, costumes, dramaturgy and schedule, from the first spotlight to the last applause.  <\/p><p>Every weekend, the Cirque du Burlesque transforms the Lieschen Mueller into a sensual burlesque theater. International burlesque artists, aerial artistry, circus acts, comedy and live music merge into a show program lasting several hours that is as breathtaking as Berlin itself. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-90419cb elementor-widget elementor-widget-heading\" data-id=\"90419cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Always fully booked - our show evenings<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-333e2c9 elementor-widget elementor-widget-text-editor\" data-id=\"333e2c9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>The Cirque du Burlesque shows are among the most sought-after burlesque experiences in Berlin: tickets are in high demand and <a href=\"https:\/\/lieschen-mueller.com\/en\/book-table-berlin-alexanderplatz\/\">advance booking<\/a> is highly recommended.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-aae7d88 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"aae7d88\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-61043cf\" data-id=\"61043cf\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f805bb9 elementor-widget elementor-widget-heading\" data-id=\"f805bb9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Showbooking, Events &amp; Creative Direction<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f4e0a5d elementor-widget elementor-widget-text-editor\" data-id=\"f4e0a5d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Behind the scenes, a well-coordinated team ensures that the atmosphere, cast and program are just right.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e18627e elementor-widget elementor-widget-heading\" data-id=\"e18627e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Costumes, dramaturgy &amp; creative details<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4ee4a8d elementor-widget elementor-widget-text-editor\" data-id=\"4ee4a8d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Cirque du Burlesque is not just about acts, but also about a well thought-out overall concept: costumes, lighting, music, moderation and transitions are planned in such a way that the evening works like a common thread. The result is a show that is not just a series of individual acts, but a sensual theatrical experience with many small details that are discovered bit by bit. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-496bb1a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"496bb1a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ce552d5\" data-id=\"ce552d5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-73265e5 elementor-widget elementor-widget-heading\" data-id=\"73265e5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Nikkie Lulaby - Event Manager &amp; Head of Show booking<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-66360ea elementor-widget elementor-widget-text-editor\" data-id=\"66360ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nikkie Lulaby is responsible for booking and supervising the international Cirque du Burlesque show.<\/p><p>As a classically trained event manager and part of the project from the very beginning, he knows every facet of Lieschen Mueller &#8211; from the first casting rounds to the final applause in a sold-out show.<\/p><p>He is responsible for show booking, planning the processes and looking after the artists on site. At the same time, he brings his creative side to the table, designing costumes and developing show elements that surprise the audience and remain in their memories. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-466b0b9\" data-id=\"466b0b9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1e3f1c7 elementor-widget elementor-widget-image\" data-id=\"1e3f1c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/lieschen-mueller.com\/wp-content\/uploads\/2026\/05\/Kachel-Nikkie-Lulaby-1024x1024.webp\" class=\"attachment-large size-large wp-image-15904\" alt=\"\" srcset=\"https:\/\/lieschen-mueller.com\/wp-content\/uploads\/2026\/05\/Kachel-Nikkie-Lulaby-1024x1024.webp 1024w, https:\/\/lieschen-mueller.com\/wp-content\/uploads\/2026\/05\/Kachel-Nikkie-Lulaby-300x300.webp 300w, https:\/\/lieschen-mueller.com\/wp-content\/uploads\/2026\/05\/Kachel-Nikkie-Lulaby-150x150.webp 150w, https:\/\/lieschen-mueller.com\/wp-content\/uploads\/2026\/05\/Kachel-Nikkie-Lulaby-768x768.webp 768w, https:\/\/lieschen-mueller.com\/wp-content\/uploads\/2026\/05\/Kachel-Nikkie-Lulaby.webp 1200w\" sizes=\"(max-width: 800px) 100vw, 800px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-351ec6a elementor-widget elementor-widget-spacer\" data-id=\"351ec6a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-493bb62 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"493bb62\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-05302b2\" data-id=\"05302b2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-944a1e5 elementor-widget elementor-widget-heading\" data-id=\"944a1e5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Torsten Karlsch - Concept &amp; Brand<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-22adcd2 elementor-widget elementor-widget-text-editor\" data-id=\"22adcd2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Behind Lieschen Mueller is the conceptual work of Torsten Karlsch, brand creator and experience designer, who brings international show worlds to Berlin with Peppermint.<\/p><p>He develops concepts in which interior and lighting design, live entertainment and gastronomy are interlinked in such a way that artists from Las Vegas, Canada, Rome, Madrid, Australia, the USA, England, Brazil and many other countries find a common stage.<\/p><p>His claim: a place where the Berlin scene, international burlesque stars and guests from all over the world meet on an equal footing &#8211; glamorous, but warm and never aloof.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ce41dd7\" data-id=\"ce41dd7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b0ee47e elementor-widget elementor-widget-image\" data-id=\"b0ee47e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/lieschen-mueller.com\/wp-content\/uploads\/2026\/05\/Kachel-Torsten-Karlsch-Peppermint-Brands-1024x1024.webp\" class=\"attachment-large size-large wp-image-15905\" alt=\"About Lieschen Mueller: Torsten Karlsch Creative Concept &amp; Brand\" srcset=\"https:\/\/lieschen-mueller.com\/wp-content\/uploads\/2026\/05\/Kachel-Torsten-Karlsch-Peppermint-Brands-1024x1024.webp 1024w, https:\/\/lieschen-mueller.com\/wp-content\/uploads\/2026\/05\/Kachel-Torsten-Karlsch-Peppermint-Brands-300x300.webp 300w, https:\/\/lieschen-mueller.com\/wp-content\/uploads\/2026\/05\/Kachel-Torsten-Karlsch-Peppermint-Brands-150x150.webp 150w, https:\/\/lieschen-mueller.com\/wp-content\/uploads\/2026\/05\/Kachel-Torsten-Karlsch-Peppermint-Brands-768x768.webp 768w, https:\/\/lieschen-mueller.com\/wp-content\/uploads\/2026\/05\/Kachel-Torsten-Karlsch-Peppermint-Brands.webp 1200w\" sizes=\"(max-width: 800px) 100vw, 800px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f5cc512 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f5cc512\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bac89b2\" data-id=\"bac89b2\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-98dc782 elementor-widget elementor-widget-heading\" data-id=\"98dc782\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Bar, Cocktails &amp; International Clientele<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5b79acf elementor-widget elementor-widget-text-editor\" data-id=\"5b79acf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Lieschen Mueller is also a bar for friends of sophisticated drinking culture: the glittering <a href=\"https:\/\/lieschen-mueller.com\/en\/circus-cocktail-bar-tv-tower-berlin\/\">circus bar<\/a> offers over 150 cocktail and gin creations, as well as champagne, wine and selected spirits.<\/p><p>  This is where Berliners and guests from all over the world meet before and after the curtain falls on the show &#8211; a place to arrive, be amazed and continue the party.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-85da7a8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"85da7a8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e50dfe7\" data-id=\"e50dfe7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a3d5527 elementor-widget elementor-widget-heading\" data-id=\"a3d5527\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Hundreds of cocktails &amp; signature drinks<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cfab171 elementor-widget elementor-widget-text-editor\" data-id=\"cfab171\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>The <a href=\"https:\/\/lieschen-mueller.com\/en\/bar-menu\/\">bar menu<\/a> includes classics as well as its own signature drinks that perfectly match the burlesque atmosphere: sensual, playful, photogenic and served with great attention to detail. Whether before dinner, during a break in the show or at the end &#8211; the bar is a central part of the experience and ensures that no glass stays empty for long. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5c71bbe elementor-widget elementor-widget-heading\" data-id=\"5c71bbe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Bar manager Melissa Krohn - young power behind the bar<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1bc0b55 elementor-widget elementor-widget-text-editor\" data-id=\"1bc0b55\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>At Lieschen M\u00fcller, bar manager Melissa Krohn, one of Berlin&#8217;s youngest female bar managers, creates an international bar feeling in the heart of the capital.<\/p><p>Her dynamism, her speed and her sure instinct for guests make the nights at Lieschen Mueller so special &#8211; this is where international glamor shows meet a bar manager who is completely absorbed in this whirlwind of light, music and applause.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ca47e71\" data-id=\"ca47e71\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d6438dc elementor-widget elementor-widget-image\" data-id=\"d6438dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/lieschen-mueller.com\/wp-content\/uploads\/2026\/05\/Kachel-Barchefin-Melissa-Krohn-1024x1024.webp\" class=\"attachment-large size-large wp-image-15906\" alt=\"About Lieschen Mueller: Bar manager Melissa Krohn\" srcset=\"https:\/\/lieschen-mueller.com\/wp-content\/uploads\/2026\/05\/Kachel-Barchefin-Melissa-Krohn-1024x1024.webp 1024w, https:\/\/lieschen-mueller.com\/wp-content\/uploads\/2026\/05\/Kachel-Barchefin-Melissa-Krohn-300x300.webp 300w, https:\/\/lieschen-mueller.com\/wp-content\/uploads\/2026\/05\/Kachel-Barchefin-Melissa-Krohn-150x150.webp 150w, https:\/\/lieschen-mueller.com\/wp-content\/uploads\/2026\/05\/Kachel-Barchefin-Melissa-Krohn-768x768.webp 768w, https:\/\/lieschen-mueller.com\/wp-content\/uploads\/2026\/05\/Kachel-Barchefin-Melissa-Krohn.webp 1200w\" sizes=\"(max-width: 800px) 100vw, 800px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-892135b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"892135b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-806602f\" data-id=\"806602f\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2bc5099 elementor-widget elementor-widget-heading\" data-id=\"2bc5099\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Berlin Cuisine &amp; Show Dinner<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fa972ea elementor-widget elementor-widget-text-editor\" data-id=\"fa972ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>In addition to the bar, the kitchen also plays an important role in the Cirque du Burlesque experience.<br>Here, German and Berlin dishes are designed to match the show, the schedule and the international audience.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-342fcb4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"342fcb4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-41dd962\" data-id=\"41dd962\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4d6bf5a elementor-widget elementor-widget-heading\" data-id=\"4d6bf5a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Teresa Bott - Event and show kitchen for international guests<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fd56304 elementor-widget elementor-widget-text-editor\" data-id=\"fd56304\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Head chef Teresa Bott has experience in fine dining, variety theaters and event catering.<\/p><p>At Lieschen M\u00fcller, Teresa Bott is responsible for a kitchen that is designed like the house itself: as an event and show kitchen for an international audience.<\/p><p>She translates German favorites into creative, service-oriented concepts that go well with fully booked burlesque shows, international guests and long evenings at the bar.<\/p><p>Whether sharing plates for groups, show menus that can be served quickly or snacks for late-night drinks &#8211; her kitchen is planned to reconcile high quality, great processes and the special moment on stage.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a762d1f elementor-align-center elementor-widget elementor-widget-button\" data-id=\"a762d1f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/lieschen-mueller.com\/en\/menu-berlin-restaurant-alexanderplatz\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Have a Look at the Food Menu<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4dac1cb\" data-id=\"4dac1cb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3c8113d elementor-widget elementor-widget-image\" data-id=\"3c8113d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/lieschen-mueller.com\/wp-content\/uploads\/2026\/05\/Kachel-Teresa-Bott-1024x1024.webp\" class=\"attachment-large size-large wp-image-15907\" alt=\"About Lieschen Mueller Teresa Bott Head Chef\" srcset=\"https:\/\/lieschen-mueller.com\/wp-content\/uploads\/2026\/05\/Kachel-Teresa-Bott-1024x1024.webp 1024w, https:\/\/lieschen-mueller.com\/wp-content\/uploads\/2026\/05\/Kachel-Teresa-Bott-300x300.webp 300w, https:\/\/lieschen-mueller.com\/wp-content\/uploads\/2026\/05\/Kachel-Teresa-Bott-150x150.webp 150w, https:\/\/lieschen-mueller.com\/wp-content\/uploads\/2026\/05\/Kachel-Teresa-Bott-768x768.webp 768w, https:\/\/lieschen-mueller.com\/wp-content\/uploads\/2026\/05\/Kachel-Teresa-Bott.webp 1200w\" sizes=\"(max-width: 800px) 100vw, 800px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4ce336d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4ce336d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c29c92f\" data-id=\"c29c92f\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7a175fe elementor-widget elementor-widget-heading\" data-id=\"7a175fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Lieschen Mueller as an event location<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ef278a7 elementor-widget elementor-widget-text-editor\" data-id=\"ef278a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>The Lieschen Mueller is not only a show club, but also a special <a href=\"https:\/\/lieschen-mueller.com\/en\/events-celebrations-berlin-alexanderplatz\/\">event location<\/a> in Berlin-Mitte.<br>Corporate events, group evenings, exclusive rentals or special private parties can be combined with a burlesque show, dinner and drinks &#8211; in the middle of Alexanderplatz, directly under the TV tower<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4cc5ba9 elementor-widget elementor-widget-heading\" data-id=\"4cc5ba9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Company parties, groups &amp; exclusive evenings<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f125fcf elementor-widget elementor-widget-text-editor\" data-id=\"f125fcf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Whether team event, customer event, Christmas party or anniversary &#8211; the Lieschen Mueller offers packages for groups with show, menu and drinks.lieschen-mueller+1<br>On request, areas or entire evenings can be individually designed, including branding elements, own program items or special surprises on stage<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1e7e5e6 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"1e7e5e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/lieschen-mueller.com\/en\/events-celebrations-berlin-alexanderplatz\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Celebrate at Lieschen Mueller<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0c21c19 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0c21c19\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-66aa8bf\" data-id=\"66aa8bf\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-76cc484 elementor-widget elementor-widget-spacer\" data-id=\"76cc484\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a010791 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a010791\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-bda2b35\" data-id=\"bda2b35\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b96f0fb\" data-id=\"b96f0fb\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d501ca2 elementor-widget elementor-widget-heading\" data-id=\"d501ca2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">A Must-See in Berlin!<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b3fb392 elementor-widget elementor-widget-heading\" data-id=\"b3fb392\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Cirque du Burlesque Berlin<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f1410bd elementor-widget elementor-widget-heading\" data-id=\"f1410bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">New Burlesque And Moderne Circus<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-36db301 elementor-widget elementor-widget-text-editor\" data-id=\"36db301\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Cirque du Burlesque at Lieschen Mueller im Parterre is a show as breathtaking as Berlin itself: cool, sexy, a little bit naughty, cheeky, loud, funny&#8230; and guaranteed never boring!<\/p><p>Let yourself be captivated by the art of entertainment theater, the charm of the wild 1920s, live music, and sparkling surprises. A show sensation right in the heart of East Berlin, directly beneath the TV Tower at Alexanderplatz!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d46f00 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"3d46f00\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg\" href=\"https:\/\/lieschen-mueller.com\/en\/cirque-du-burlesque-show-berlin\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-theater-masks\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">INFORMATION AND TICKETS <\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-f0a39d4 elementor-widget elementor-widget-spacer\" data-id=\"f0a39d4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d97c1f8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d97c1f8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-82562cb\" data-id=\"82562cb\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b3fb13e elementor-widget elementor-widget-heading\" data-id=\"b3fb13e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">FAQ - Frequently asked questions about Lieschen Mueller &amp; Cirque du Burlesque<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dccf60f elementor-widget elementor-widget-accordion\" data-id=\"dccf60f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<h3 id=\"elementor-tab-title-2311\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2311\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">When do the Cirque du Burlesque shows take place?<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\t<div id=\"elementor-tab-content-2311\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2311\"><p>The<a href=\"https:\/\/lieschen-mueller.com\/en\/cirque-du-burlesque-show-berlin\/\"><strong> Cirque du Burlesque shows<\/strong><\/a> take place at <strong>weekends<\/strong> in the evening &#8211; with a program lasting several hours directly at Alexanderplatz.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<h3 id=\"elementor-tab-title-2312\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-2312\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Are the shows often fully booked?<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\t<div id=\"elementor-tab-content-2312\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-2312\"><p><strong>Yes<\/strong>, the shows are very popular and often sold out. We recommend <a href=\"https:\/\/lieschen-mueller.com\/en\/berlin-tickets-gift-vouchers-experiences\/\">booking tickets online in good time<\/a> and reserving a <a href=\"https:\/\/lieschen-mueller.com\/en\/book-table-berlin-alexanderplatz\/\">table<\/a>. <\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<h3 id=\"elementor-tab-title-2313\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-2313\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">What languages are the shows in?<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\t<div id=\"elementor-tab-content-2313\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-2313\"><p>The shows are designed to <strong>work<\/strong> even <strong>without a perfect knowledge of German<\/strong> &#8211; with lots of music, artistry, non-verbal comedy and international flair, ideal <strong>for Berliners and tourists.<\/strong><\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<h3 id=\"elementor-tab-title-2314\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-2314\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Can you also eat at Lieschen Mueller?<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\t<div id=\"elementor-tab-content-2314\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-2314\"><p><strong>Yes<\/strong>, there is <strong>Berlin cuisine<\/strong> and the <a href=\"https:\/\/lieschen-mueller.com\/en\/menu-berlin-restaurant-alexanderplatz\/\">menu<\/a> includes dishes to match the show.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<h3 id=\"elementor-tab-title-2315\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-2315\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Is the Lieschen Mueller suitable for JGAs, birthdays and corporate events?<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\t<div id=\"elementor-tab-content-2315\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-2315\"><p>Absolut &#8211; <strong><a href=\"https:\/\/lieschen-mueller.com\/en\/cirque-du-burlesque-show-berlin\/\">Cirque du Burlesque<\/a> is a popular experience for stag parties, birthdays, girls&#8217; evenings and corporate events.<\/strong> Suitable <strong>experience packages<\/strong> are offered in the <a href=\"https:\/\/lieschen-mueller.com\/en\/berlin-tickets-gift-vouchers-experiences\/\">online store<\/a> <\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>About us &#8211; Lieschen Mueller Cirque du Burlesque Bar, adventure restaurant &amp; show club at Alexanderplatz Our world of burlesque &amp; show entertainment Lieschen Mueller is Berlin&#8217;s crazy circus and burlesque bar directly under the TV tower &#8211; a restaurant, caf\u00e9 and show club all in one. An international burlesque and entertainment hotspot: a mix [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":15902,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ngg_post_thumbnail":0,"footnotes":""},"class_list":["post-15911","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/lieschen-mueller.com\/en\/wp-json\/wp\/v2\/pages\/15911","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lieschen-mueller.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lieschen-mueller.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lieschen-mueller.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lieschen-mueller.com\/en\/wp-json\/wp\/v2\/comments?post=15911"}],"version-history":[{"count":5,"href":"https:\/\/lieschen-mueller.com\/en\/wp-json\/wp\/v2\/pages\/15911\/revisions"}],"predecessor-version":[{"id":15920,"href":"https:\/\/lieschen-mueller.com\/en\/wp-json\/wp\/v2\/pages\/15911\/revisions\/15920"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lieschen-mueller.com\/en\/wp-json\/wp\/v2\/media\/15902"}],"wp:attachment":[{"href":"https:\/\/lieschen-mueller.com\/en\/wp-json\/wp\/v2\/media?parent=15911"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}